{"id":87689,"date":"2026-09-01T18:27:59","date_gmt":"2026-09-01T16:27:59","guid":{"rendered":"https:\/\/go-microdose.com\/blog\/preparation-a-la-dose-heroique-ta-checklist-de-preparation-en-30-jours\/"},"modified":"2026-09-01T18:29:22","modified_gmt":"2026-09-01T16:29:22","slug":"preparation-a-la-dose-heroique-ta-checklist-de-preparation-en-30-jours","status":"publish","type":"post","link":"https:\/\/go-microdose.com\/fr\/blog\/preparation-a-la-dose-heroique-ta-checklist-de-preparation-en-30-jours\/","title":{"rendered":"Pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque : ta checklist de pr\u00e9paration en 30 jours"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">La pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque consiste \u00e0 construire les bonnes bases mentales, physiques et pratiques pour une exp\u00e9rience de psilocybine \u00e0 forte dose. Une dose h\u00e9ro\u00efque, g\u00e9n\u00e9ralement 5 grammes ou plus de champignons s\u00e9ch\u00e9s (environ 15 grammes de <b>truffes fra\u00eeches<\/b>), exige respect et planification intentionnelle. Cette checklist de 30 jours te guide \u00e0 travers ce qu&rsquo;il faut organiser, ce qu&rsquo;il faut pratiquer et comment savoir quand tu es vraiment pr\u00eat.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbQu&apos;est-ce qu&apos;une dose h\u00e9ro\u00efque et pourquoi n\u00e9cessite-t-elle une pr\u00e9paration ?\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][vc_single_image image=\u00a0\u00bb87690&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css_animation=\u00a0\u00bbnone\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1788228126589{margin-top: 20px !important;margin-bottom: 50px !important;}\u00a0\u00bb el_class=\u00a0\u00bbimage-with-shadow\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">Une dose h\u00e9ro\u00efque fait r\u00e9f\u00e9rence \u00e0 une exp\u00e9rience de psilocybine \u00e0 forte dose con\u00e7ue pour dissoudre l&rsquo;ego et acc\u00e9der \u00e0 des \u00e9tats introspectifs profonds. Le terme a \u00e9t\u00e9 popularis\u00e9 par l&rsquo;ethnobotaniste Terence McKenna, qui pr\u00e9conisait de prendre 5 grammes de champignons s\u00e9ch\u00e9s dans l&rsquo;obscurit\u00e9 et le silence. Pour ceux qui travaillent avec des truffes de psilocybine fra\u00eeches comme celles disponibles chez GO Microdose, l&rsquo;\u00e9quivalent serait d&rsquo;environ 15 grammes ou plus, selon la puissance de la souche.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contrairement au microdosage, qui modifie subtilement la perception au fil du temps, une dose h\u00e9ro\u00efque peut produire des exp\u00e9riences visuelles et \u00e9motionnelles intenses, des introspections profondes et une dissolution temporaire de ton sens de soi. Ce n&rsquo;est pas r\u00e9cr\u00e9atif. C&rsquo;est un travail psychologique. C&rsquo;est pourquoi la pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque est importante. Entrer sans pr\u00e9paration augmente le risque d&rsquo;anxi\u00e9t\u00e9 accablante, d&rsquo;int\u00e9gration difficile ou de r\u00e9ponse traumatique \u00e0 l&rsquo;exp\u00e9rience.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cette checklist suppose que tu as d\u00e9j\u00e0 eu des exp\u00e9riences \u00e0 faible dose (2-5 grammes de truffes fra\u00eeches ou 0,5-1,5 grammes de champignons s\u00e9ch\u00e9s) et que tu comprends comment la psilocybine t&rsquo;affecte personnellement. Si tu es compl\u00e8tement novice, commence par notre <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/blog\/effets-du-dosage-de-truffes-3-experiences-honnetes-a-5-10-et-15-grammes\/\">guide de dosage des truffes<\/a> pour te familiariser d&rsquo;abord.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbSemaines 1-2 : Travail de base mental et \u00e9motionnel\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">Les deux premi\u00e8res semaines sont consacr\u00e9es \u00e0 clarifier ton intention et \u00e0 stabiliser ton \u00e9tat mental.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\"><b>D\u00e9finis une intention claire<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9cris pourquoi tu veux prendre une dose h\u00e9ro\u00efque. Cherches-tu \u00e0 gu\u00e9rir d&rsquo;un traumatisme ? \u00c0 explorer des questions existentielles ? \u00c0 affronter la peur ou le chagrin ? Ton intention agira comme une ancre lorsque l&rsquo;exp\u00e9rience deviendra intense. \u00c9vite les objectifs vagues comme \u00ab Je veux explorer \u00bb. Sois pr\u00e9cis : \u00ab Je veux comprendre ma relation avec mon p\u00e8re \u00bb ou \u00ab Je veux me lib\u00e9rer de la honte que je porte concernant mon corps \u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>V\u00e9rifie ton \u00e9tat mental de base<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La psilocybine \u00e0 forte dose n&rsquo;est pas recommand\u00e9e en cas de d\u00e9tresse psychologique aigu\u00eb, de d\u00e9pression s\u00e9v\u00e8re non trait\u00e9e ou de psychose active. Si tu es actuellement en crise ou sous m\u00e9dication psychiatrique (en particulier des ISRS ou des antipsychotiques), consulte un th\u00e9rapeute inform\u00e9 sur les psych\u00e9d\u00e9liques avant de continuer. Les doses h\u00e9ro\u00efques amplifient tout ce qui est pr\u00e9sent dans ton psychisme. La stabilit\u00e9 d&rsquo;abord, l&rsquo;exploration ensuite.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Commence une pratique de r\u00e9flexion quotidienne<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Commence \u00e0 tenir un journal pendant 10 minutes chaque matin. Note tes sch\u00e9mas \u00e9motionnels, tes pens\u00e9es r\u00e9currentes et toute r\u00e9sistance ou excitation concernant l&rsquo;exp\u00e9rience \u00e0 venir. Cela te pr\u00e9pare \u00e0 l&rsquo;introspection et te donne une base de r\u00e9f\u00e9rence pour comparer les insights post-voyage.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbSemaines 2-3 : Pr\u00e9paration physique et ajustements de style de vie\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">L&rsquo;\u00e9tat de ton corps influence la qualit\u00e9 de l&rsquo;exp\u00e9rience. Utilise ces deux semaines pour optimiser ta pr\u00e9paration physique.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\"><b>R\u00e9duis ou \u00e9limine l&rsquo;alcool et le cannabis<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ces deux substances \u00e9moussent la clart\u00e9 \u00e9motionnelle et peuvent interf\u00e9rer avec les effets de la psilocybine. Vise au moins 7 \u00e0 10 jours de sobri\u00e9t\u00e9 avant ta dose h\u00e9ro\u00efque. Pour plus de contexte sur cette interaction, consulte notre guide sur le <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/blog\/microdosage-et-alcool\/\">microdosage et l&rsquo;alcool<\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Optimise ton sommeil<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La fatigue amplifie l&rsquo;anxi\u00e9t\u00e9 et r\u00e9duit la r\u00e9silience \u00e9motionnelle. Priorise 7 \u00e0 8 heures de sommeil de qualit\u00e9 chaque nuit. Envisage d&rsquo;ajouter du <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/produit\/complexe-de-bisglycinate-de-magnesium\/\">bisglycinate de magn\u00e9sium<\/a> ou des <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/produit\/gummies-sommeil-5-htp\/\">gommes de 5-HTP pour le sommeil<\/a> si tu as du mal \u00e0 te reposer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Am\u00e9liore ton alimentation<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9vite les aliments lourds et transform\u00e9s dans les 48 heures pr\u00e9c\u00e9dant ton voyage. De nombreux utilisateurs exp\u00e9riment\u00e9s je\u00fbnent pendant 4 \u00e0 6 heures avant pour r\u00e9duire les naus\u00e9es et augmenter l&rsquo;absorption de la psilocybine. Le jour m\u00eame, un petit-d\u00e9jeuner l\u00e9ger (fruits, toasts) est g\u00e9n\u00e9ralement acceptable si tu doses l&rsquo;apr\u00e8s-midi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Bouge ton corps<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;exercice physique r\u00e9duit l&rsquo;anxi\u00e9t\u00e9 de base et am\u00e9liore la r\u00e9gulation \u00e9motionnelle. Vise 20 \u00e0 30 minutes de mouvement quotidien : marche, yoga ou tout ce qui te fait du bien. Tu veux entrer dans l&rsquo;exp\u00e9rience ancr\u00e9 dans ton corps, pas pi\u00e9g\u00e9 dans ta t\u00eate.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbSemaines 3-4 : Configuration logistique et environnementale\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">La derni\u00e8re semaine est consacr\u00e9e \u00e0 l&rsquo;organisation des d\u00e9tails pratiques qui te permettront de t&rsquo;abandonner pleinement.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\"><b>Choisis ton environnement avec soin<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tu as besoin d&rsquo;un espace s\u00fbr, priv\u00e9 et confortable o\u00f9 tu ne seras pas interrompu pendant 6 \u00e0 8 heures. La maison est g\u00e9n\u00e9ralement le meilleur endroit. Nettoie l&rsquo;espace au pr\u00e9alable. Aie des couvertures, des oreillers et un \u00e9clairage tamis\u00e9 \u00e0 disposition. Certaines personnes pr\u00e9f\u00e8rent l&rsquo;obscurit\u00e9 totale ; d&rsquo;autres aiment une lumi\u00e8re naturelle douce. Teste ton environnement \u00e0 l&rsquo;avance.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Organise la pr\u00e9sence d&rsquo;un accompagnateur (fortement recommand\u00e9)<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un accompagnateur sobre et exp\u00e9riment\u00e9 apporte s\u00e9curit\u00e9 et r\u00e9confort. Choisis quelqu&rsquo;un de calme, sans jugement et familier avec les psych\u00e9d\u00e9liques. Son r\u00f4le n&rsquo;est pas de guider ou d&rsquo;interpr\u00e9ter, mais d&rsquo;\u00eatre pr\u00e9sent et d&rsquo;aider si tu as besoin d&rsquo;eau, d&rsquo;une couverture ou d&rsquo;\u00eatre rassur\u00e9 sur ta s\u00e9curit\u00e9. Discute des limites et des attentes avant le jour J.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Pr\u00e9pare ta dose \u00e0 l&rsquo;avance<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour les truffes fra\u00eeches, 15 \u00e0 20 grammes est une fourchette courante pour une dose h\u00e9ro\u00efque, selon la souche. GO Microdose propose <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/produit\/truffe-utopia\/\">Utopia<\/a> et <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/produit\/truffe-hollandia\/\">Hollandia<\/a> pour les exp\u00e9riences \u00e0 forte dose. P\u00e8se ta dose avec pr\u00e9cision \u00e0 l&rsquo;aide d&rsquo;une <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/produit\/balance-de-precision\/\">balance de pr\u00e9cision<\/a>. M\u00e2che soigneusement ou pr\u00e9pare en infusion. Conserve les truffes correctement jusqu&rsquo;au jour J (non ouvertes, r\u00e9frig\u00e9r\u00e9es).<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Lib\u00e8re ton calendrier<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bloque le jour du voyage et le jour suivant. Pas de travail, pas d&rsquo;obligations sociales, pas de responsabilit\u00e9s. Tu auras besoin de temps pour te reposer et commencer l&rsquo;int\u00e9gration. Fais savoir \u00e0 tes amis proches ou colocataires que tu seras indisponible.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Cr\u00e9e une playlist ou choisis le silence<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Beaucoup pr\u00e9f\u00e8rent la musique instrumentale (classique, ambiante ou playlists psych\u00e9d\u00e9liques s\u00e9lectionn\u00e9es). D&rsquo;autres suivent les conseils de McKenna et s&rsquo;assoient en silence. D\u00e9cide \u00e0 l&rsquo;avance, mais reste flexible. Aie des \u00e9couteurs et un haut-parleur pr\u00eats.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><b>Pr\u00e9pare un soutien \u00e0 l&rsquo;int\u00e9gration<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trouve un ami de confiance, un th\u00e9rapeute ou un cercle d&rsquo;int\u00e9gration pour discuter de l&rsquo;exp\u00e9rience dans les 48 \u00e0 72 heures. Le traitement est l\u00e0 o\u00f9 la vraie valeur \u00e9merge. Ne saute pas cette \u00e9tape.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bb48 derni\u00e8res heures : Derni\u00e8res v\u00e9rifications avant que la pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque ne soit compl\u00e8te\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">Dans les deux jours pr\u00e9c\u00e9dant ton voyage, ralentis. R\u00e9duis la stimulation : moins de temps d&rsquo;\u00e9cran, moins d&rsquo;actualit\u00e9s, moins d&rsquo;interactions sociales. Passe du temps dans la nature si possible. Revois ton intention. Rappelle-toi que tout ce qui surgit est temporaire et fait partie du processus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le matin m\u00eame, mange l\u00e9g\u00e8rement et t\u00f4t. \u00c9vite la caf\u00e9ine si elle te rend nerveux. Douche-toi, habille-toi confortablement et arrange ton espace. Aie de l&rsquo;eau, des mouchoirs, un seau (pour les naus\u00e9es) et un journal \u00e0 port\u00e9e de main. \u00c9teins ton t\u00e9l\u00e9phone ou mets-le en mode avion.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Avant de doser, prends un moment de gratitude. Tu as fait le travail. Tu es aussi pr\u00eat que possible. Fais confiance au processus, fais confiance \u00e0 la m\u00e9decine et fais-toi confiance.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbQue faire si tu r\u00e9alises que tu n&apos;es pas pr\u00eat\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">Si, \u00e0 un moment quelconque de ce processus de 30 jours, tu ressens un doute important, de la peur ou de l&rsquo;instabilit\u00e9, reporte l&rsquo;exp\u00e9rience. Il n&rsquo;y a pas de date limite. Les doses h\u00e9ro\u00efques ne devraient jamais \u00eatre forc\u00e9es. Il est bien pr\u00e9f\u00e9rable d&rsquo;attendre que les conditions soient r\u00e9unies plut\u00f4t que de pers\u00e9v\u00e9rer et de vivre une exp\u00e9rience d\u00e9stabilisante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les signes que tu pourrais vouloir attendre incluent une anxi\u00e9t\u00e9 persistante concernant le voyage (pas de la nervosit\u00e9, mais de l&rsquo;appr\u00e9hension), un traumatisme ou une perte r\u00e9cente que tu n&rsquo;as pas trait\u00e9s, des conflits dans tes relations proches, ou le sentiment d&rsquo;\u00eatre sous pression par d&rsquo;autres. \u00c9coute ton instinct. Les truffes seront toujours l\u00e0 quand tu seras pr\u00eat.<\/span>[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbQuestions fr\u00e9quentes\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\"><b>Combien de truffes fra\u00eeches \u00e9quivalent \u00e0 une dose h\u00e9ro\u00efque de 5 grammes de champignons s\u00e9ch\u00e9s ?<\/b><\/span><\/p>\n<p>Environ 15 grammes de truffes de psilocybine fra\u00eeches \u00e9quivalent \u00e0 environ 5 grammes s\u00e9ch\u00e9s, bien que la puissance varie selon la souche. Pour une v\u00e9ritable dose h\u00e9ro\u00efque avec des truffes fra\u00eeches, de nombreux utilisateurs prennent 15 \u00e0 20 grammes d&rsquo;une vari\u00e9t\u00e9 forte comme Utopia ou Hollandia.<\/p>\n<p><b>Puis-je prendre une dose h\u00e9ro\u00efque seul, ou ai-je besoin d&rsquo;un accompagnateur ?<\/b><\/p>\n<p>Tu peux voyager seul si tu es exp\u00e9riment\u00e9 et que tu te sens confiant, mais un accompagnateur sobre est fortement recommand\u00e9 pour les premi\u00e8res doses h\u00e9ro\u00efques. Il assure ta s\u00e9curit\u00e9 physique et ton r\u00e9confort \u00e9motionnel si l&rsquo;exp\u00e9rience devient accablante.<\/p>\n<p><b>Dois-je je\u00fbner avant une dose h\u00e9ro\u00efque ?<\/b><\/p>\n<p>Beaucoup de gens je\u00fbnent pendant 4 \u00e0 6 heures avant de doser pour r\u00e9duire les naus\u00e9es et am\u00e9liorer l&rsquo;absorption. Un petit-d\u00e9jeuner l\u00e9ger et t\u00f4t est g\u00e9n\u00e9ralement acceptable si tu doses l&rsquo;apr\u00e8s-midi. \u00c9vite les repas lourds ou gras.<\/p>\n<p><b>Que faire si je fais un \u00ab bad trip \u00bb pendant ma dose h\u00e9ro\u00efque ?<\/b><\/p>\n<p>Rappelle-toi que l&rsquo;exp\u00e9rience est temporaire et que tu es en s\u00e9curit\u00e9. Respire lentement, change de position ou d&rsquo;environnement, et demande \u00e0 ton accompagnateur de te rassurer. Les moments difficiles rec\u00e8lent souvent le plus grand potentiel d&rsquo;introspection. Abandonne-toi plut\u00f4t que de r\u00e9sister.<\/p>\n<p><b>Combien de temps dois-je attendre entre une dose h\u00e9ro\u00efque et la reprise du microdosage ?<\/b><\/p>\n<p>Attends au moins 1 \u00e0 2 semaines apr\u00e8s une dose h\u00e9ro\u00efque avant de reprendre le microdosage. Cela permet \u00e0 la tol\u00e9rance de se r\u00e9initialiser et te donne de l&rsquo;espace pour int\u00e9grer l&rsquo;exp\u00e9rience. Pour en savoir plus sur la tol\u00e9rance, consulte notre guide sur la <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/blog\/reinitialisation-de-la-tolerance-au-microdosage-5-moyens-simples-de-retrouver-les-effets\/\">r\u00e9initialisation de la tol\u00e9rance au microdosage<\/a>.<\/p>\n<p><b>Ai-je besoin d&rsquo;une exp\u00e9rience psych\u00e9d\u00e9lique pr\u00e9alable avant de tenter une dose h\u00e9ro\u00efque ?<\/b><\/p>\n<p>Oui. Les doses h\u00e9ro\u00efques ne sont pas pour les d\u00e9butants. Tu devrais avoir plusieurs exp\u00e9riences \u00e0 dose mod\u00e9r\u00e9e (5-10 grammes de truffes fra\u00eeches ou 1-3 grammes de champignons s\u00e9ch\u00e9s) \u00e0 ton actif afin de comprendre comment la psilocybine affecte ton corps et ton esprit.[\/vc_column_text]<\/p>\n<p>[vc_custom_heading text=\u00a0\u00bbConclusion\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p>[vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<span style=\"font-weight: 400;\">La pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque ne consiste pas \u00e0 \u00e9liminer la peur, mais \u00e0 cr\u00e9er les conditions int\u00e9rieures et ext\u00e9rieures qui te permettent d&rsquo;aborder l&rsquo;exp\u00e9rience avec respect et ouverture. Utilise ces 30 jours pour stabiliser ton esprit, renforcer ton corps et organiser le soutien pratique dont tu as besoin. Le moment venu, fais confiance au travail que tu as accompli. Explore notre <a style=\"color: #c8954a; text-decoration: underline; font-weight: 500;\" href=\"https:\/\/go-microdose.com\/fr\/boutique\/\">gamme de truffes \u00e0 forte dose<\/a> lorsque tu seras pr\u00eat \u00e0 passer \u00e0 l&rsquo;\u00e9tape suivante.<\/span>[\/vc_column_text][vc_btn title=\u00a0\u00bbCommencer les achats\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Fgo-microdose.com%2Ffr%2Fboutique%2F|\u00a0\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque demande plus que du courage. Cette checklist de 30 jours couvre la pr\u00e9paration mentale, physique et logistique pour ta premi\u00e8re exp\u00e9rience de 5g et plus.<\/p>\n","protected":false},"author":5548,"featured_media":87690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_description":"La pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque demande plus que du courage. Cette checklist de 30 jours couvre la pr\u00e9paration mentale, physique et logistique pour ta premi\u00e8re exp\u00e9rience de 5g et plus.","rank_math_focus_keyword":"pr\u00e9paration \u00e0 la dose h\u00e9ro\u00efque","rank_math_title":"","footnotes":""},"categories":[161],"tags":[],"class_list":["post-87689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/posts\/87689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/users\/5548"}],"replies":[{"embeddable":true,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/comments?post=87689"}],"version-history":[{"count":6,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/posts\/87689\/revisions"}],"predecessor-version":[{"id":87696,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/posts\/87689\/revisions\/87696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/media\/87690"}],"wp:attachment":[{"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/media?parent=87689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/categories?post=87689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/go-microdose.com\/fr\/wp-json\/wp\/v2\/tags?post=87689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}